{"id":933,"count":2,"description":"hotel chain casa andina private collecion ","link":"https:\/\/southamericaplanet.com\/es\/tag\/casa-andina-private-collecion\/","name":"casa andina private collecion","slug":"casa-andina-private-collecion","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>casa andina private collecion Archives -<\/title>\n<meta name=\"description\" content=\"casa andina private collecion\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/southamericaplanet.com\/es\/tag\/casa-andina-private-collecion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"casa andina private collecion Archives -\" \/>\n<meta property=\"og:description\" content=\"casa andina private collecion\" \/>\n<meta property=\"og:image\" content=\"https:\/\/southamericaplanet.com\/wp-content\/uploads\/2021\/09\/southamericaplanet.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/southamericaplanet.com\/nl\/tag\/casa-andina-private-collecion\/\",\"url\":\"https:\/\/southamericaplanet.com\/nl\/tag\/casa-andina-private-collecion\/\",\"name\":\"casa andina private collecion Archives -\",\"isPartOf\":{\"@id\":\"https:\/\/southamericaplanet.com\/#website\"},\"description\":\"casa andina private collecion\",\"breadcrumb\":{\"@id\":\"https:\/\/southamericaplanet.com\/nl\/tag\/casa-andina-private-collecion\/#breadcrumb\"},\"inLanguage\":\"es-PE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/southamericaplanet.com\/nl\/tag\/casa-andina-private-collecion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/southamericaplanet.com\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"casa andina private collecion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/southamericaplanet.com\/#website\",\"url\":\"https:\/\/southamericaplanet.com\/\",\"name\":\"South America Planet\",\"description\":\"Agente de viajes Sudam\u00e9rica, viajes a Per\u00fa, Bolivia, Argentina, Chile, Colombia, Ecuador, tambi\u00e9n trekking, operador oficial incatrail\",\"publisher\":{\"@id\":\"https:\/\/southamericaplanet.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/southamericaplanet.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-PE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/southamericaplanet.com\/#organization\",\"name\":\"South America Planet\",\"url\":\"https:\/\/southamericaplanet.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-PE\",\"@id\":\"https:\/\/southamericaplanet.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/southamericaplanet.com\/wp-content\/uploads\/2016\/11\/114-logo.yj6w.jpg\",\"contentUrl\":\"https:\/\/southamericaplanet.com\/wp-content\/uploads\/2016\/11\/114-logo.yj6w.jpg\",\"width\":140,\"height\":140,\"caption\":\"South America Planet\"},\"image\":{\"@id\":\"https:\/\/southamericaplanet.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Southamericaplanet\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"casa andina private collecion Archives -","description":"casa andina private collecion","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/southamericaplanet.com\/es\/tag\/casa-andina-private-collecion\/","og_locale":"es_ES","og_type":"article","og_title":"casa andina private collecion Archives -","og_description":"casa andina private collecion","og_image":[{"width":1200,"height":627,"url":"https:\/\/southamericaplanet.com\/wp-content\/uploads\/2021\/09\/southamericaplanet.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/southamericaplanet.com\/nl\/tag\/casa-andina-private-collecion\/","url":"https:\/\/southamericaplanet.com\/nl\/tag\/casa-andina-private-collecion\/","name":"casa andina private collecion Archives -","isPartOf":{"@id":"https:\/\/southamericaplanet.com\/#website"},"description":"casa andina private collecion","breadcrumb":{"@id":"https:\/\/southamericaplanet.com\/nl\/tag\/casa-andina-private-collecion\/#breadcrumb"},"inLanguage":"es-PE"},{"@type":"BreadcrumbList","@id":"https:\/\/southamericaplanet.com\/nl\/tag\/casa-andina-private-collecion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/southamericaplanet.com\/nl\/"},{"@type":"ListItem","position":2,"name":"casa andina private collecion"}]},{"@type":"WebSite","@id":"https:\/\/southamericaplanet.com\/#website","url":"https:\/\/southamericaplanet.com\/","name":"South America Planet","description":"Agente de viajes Sudam\u00e9rica, viajes a Per\u00fa, Bolivia, Argentina, Chile, Colombia, Ecuador, tambi\u00e9n trekking, operador oficial incatrail","publisher":{"@id":"https:\/\/southamericaplanet.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/southamericaplanet.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-PE"},{"@type":"Organization","@id":"https:\/\/southamericaplanet.com\/#organization","name":"South America Planet","url":"https:\/\/southamericaplanet.com\/","logo":{"@type":"ImageObject","inLanguage":"es-PE","@id":"https:\/\/southamericaplanet.com\/#\/schema\/logo\/image\/","url":"https:\/\/southamericaplanet.com\/wp-content\/uploads\/2016\/11\/114-logo.yj6w.jpg","contentUrl":"https:\/\/southamericaplanet.com\/wp-content\/uploads\/2016\/11\/114-logo.yj6w.jpg","width":140,"height":140,"caption":"South America Planet"},"image":{"@id":"https:\/\/southamericaplanet.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Southamericaplanet"]}]}},"_links":{"self":[{"href":"https:\/\/southamericaplanet.com\/es\/wp-json\/wp\/v2\/tags\/933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/southamericaplanet.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/southamericaplanet.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/southamericaplanet.com\/es\/wp-json\/wp\/v2\/posts?tags=933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}